{"id":1849,"date":"2022-11-28T09:32:10","date_gmt":"2022-11-28T08:32:10","guid":{"rendered":"https:\/\/hecht.ag\/it\/?page_id=1849"},"modified":"2024-03-28T09:14:08","modified_gmt":"2024-03-28T08:14:08","slug":"servizio-consulenza","status":"publish","type":"page","link":"https:\/\/hecht.ag\/it\/servizio-consulenza\/","title":{"rendered":"SERVIZIO &#038; CONSULENZA\u200b"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1849\" class=\"elementor elementor-1849\" data-elementor-settings=\"{&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3c26d340 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3c26d340\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-45fff0b2\" data-id=\"45fff0b2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47d209cb elementor-widget elementor-widget-heading\" data-id=\"47d209cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">SERVIZIO &amp; CONSULENZA<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b57a443 elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b57a443\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0c4c9eb\" data-id=\"0c4c9eb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-06e7671 elementor-widget elementor-widget-spacer\" data-id=\"06e7671\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5296b0b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5296b0b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e02f157\" data-id=\"e02f157\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-630e39a elementor-widget elementor-widget-text-editor\" data-id=\"630e39a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Servizio completo da parte dei vostri specialisti: offriamo un servizio a tutto tondo perch\u00e9 sappiamo che la vostra produzione deve raggiungere uno speciale standard di qualit\u00e0.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31d47b6 elementor-widget elementor-widget-text-editor\" data-id=\"31d47b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong style=\"letter-spacing: 0px; word-spacing: 0em;\">Telefono:<\/strong> <a style=\"letter-spacing: 0px; word-spacing: 0em; background-color: #ffffff;\" href=\"tel:+497143815910\">+49 (0)7143-8159-10<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56305e0 elementor-mobile-align-center elementor-align-center elementor-widget elementor-widget-button\" data-id=\"56305e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#formular\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Modulo di Contatto<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1fb9906 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-google_maps\" data-id=\"1fb9906\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"google-maps\" data-borlabs-cookie-content=\"PGlmcmFtZSBsb2FkaW5nPSJsYXp5IgoJCQkJCXNyYz0iaHR0cHM6Ly9tYXBzLmdvb2dsZS5jb20vbWFwcz9xPUhlY2h0JTIwQUclMjBIZWlucmljaC1IZXJ0ei1TdHIuJTIwMy01JTIwNzQzNTQlMjBCZXNpZ2hlaW0mIzAzODt0PW0mIzAzODt6PTExJiMwMzg7b3V0cHV0PWVtYmVkJiMwMzg7aXdsb2M9bmVhciIKCQkJCQl0aXRsZT0iSGVjaHQgQUcgSGVpbnJpY2gtSGVydHotU3RyLiAzLTUgNzQzNTQgQmVzaWdoZWltIgoJCQkJCWFyaWEtbGFiZWw9IkhlY2h0IEFHIEhlaW5yaWNoLUhlcnR6LVN0ci4gMy01IDc0MzU0IEJlc2lnaGVpbSIKCQkJPjwvaWZyYW1lPg==\"><div class=\"brlbs-cmpnt-cb-preset-b brlbs-cmpnt-cb-google-maps\"> <div class=\"brlbs-cmpnt-cb-thumbnail\" style=\"background-image: url('https:\/\/hecht.ag\/it\/wp-content\/uploads\/borlabs-cookie\/5\/brlbs-cb-google-maps-main.png')\"><\/div> <div class=\"brlbs-cmpnt-cb-main\"> <div class=\"brlbs-cmpnt-cb-content\"> <p class=\"brlbs-cmpnt-cb-description\">Stai visualizzando un contenuto segnaposto da <strong>Google Maps<\/strong>. Per accedere al contenuto effettivo, clicca sul pulsante sottostante. Si prega di notare che in questo modo si condividono i dati con provider di terze parti.<\/p> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Ulteriori informazioni<\/a> <\/div> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Sblocca il contenuto<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Accetta il servizio richiesto e sblocca i contenuti<\/a> <\/div> <\/div> <\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7aef5c3 elementor-mobile-align-center elementor-align-center elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"7aef5c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#adresse\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Indirizzo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a72472e\" data-id=\"a72472e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c982c4e elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"c982c4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carosello d&#039;immagini\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 di 1\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/hecht.ag\/it\/wp-content\/uploads\/sites\/5\/2023\/02\/IMG_0436-service-team-hecht-ag-maschinenbau-1500-005.jpg\" alt=\"IMG_0436-service-team-hecht ag-maschinenbau-1500-005\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dc5f3b9 elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dc5f3b9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-872a8e9\" data-id=\"872a8e9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9da06b8 elementor-widget elementor-widget-spacer\" data-id=\"9da06b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f7e2a38 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"f7e2a38\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ee64f5a\" data-id=\"ee64f5a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e2993da elementor-widget elementor-widget-menu-anchor\" data-id=\"e2993da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"telefon\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d6381c0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d6381c0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-84a2fbe\" data-id=\"84a2fbe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2903eef elementor-widget elementor-widget-heading\" data-id=\"2903eef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">SERVIZIO TECNICO<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c8ad022 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c8ad022\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-99996b4\" data-id=\"99996b4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-12a4ee8 elementor-section-full_width elementor-hidden-tablet elementor-section-height-default elementor-section-height-default\" data-id=\"12a4ee8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-de9b16a\" data-id=\"de9b16a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f25b447 ekit-equal-height-enable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"f25b447\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <a href=\"#\" class=\"ekit_global_links\">\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text- text- icon-lef-right-aligin elementor-animation-   \">\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    Linea telefonica diretta                <\/h3>\n                        \t\t  \t<p>Siamo a vostra disposizione per telefono e per e-mail e ci occuperemo delle vostre preoccupazioni. <\/p>\n                                <\/div>\n        \n        \n                <\/div>\n                <\/a>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-0fbe424\" data-id=\"0fbe424\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a701ee ekit-equal-height-enable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"8a701ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <a href=\"#\" class=\"ekit_global_links\">\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text- text- icon-lef-right-aligin elementor-animation-   \">\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    Servizio Remoto                 <\/h3>\n                        \t\t  \t<p>I nostri tecnici dell'assistenza in ufficio sono altamente qualificati e risolvono domande e problemi tecnici \n<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n                <\/a>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-a160664\" data-id=\"a160664\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f37fe4 ekit-equal-height-enable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"0f37fe4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <a href=\"#\" class=\"ekit_global_links\">\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text- text- icon-lef-right-aligin elementor-animation-   \">\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    Servizio in loco\/ sul posto                <\/h3>\n                        \t\t  \t<p>Tecnici dell'assistenza addestrati sono costantemente sul posto con i nostri clienti - in tutto il mondo<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n                <\/a>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-4cdf11c\" data-id=\"4cdf11c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fa4c7b7 ekit-equal-height-enable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"fa4c7b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <a href=\"#\" class=\"ekit_global_links\">\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text- text- icon-lef-right-aligin elementor-animation-   \">\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    Ricambi                <\/h3>\n                        \t\t  \t<p>Tutti i pezzi di ricambio possono essere acquistati direttamente da noi. In caso di guasto, \u00e8 possibile sostituire rapidamente la parte e continuare a lavorare. Siamo lieti di aiutarvi se necessario tramite la nostra hotline o in loco.<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n                <\/a>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-4e9a2b4\" data-id=\"4e9a2b4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14a9bba ekit-equal-height-enable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"14a9bba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <a href=\"#\" class=\"ekit_global_links\">\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text- text- icon-lef-right-aligin elementor-animation-   \">\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    Corsi di formazione                <\/h3>\n                        \t\t  \t<p>Il vostro sistema HECHT dovrebbe supportare i processi nel miglior modo possibile. Addestra regolarmente il vostro personale per essere sempre aggiornato.\n<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n                <\/a>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1f45792 elementor-hidden-desktop elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1f45792\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-dcfa5fa\" data-id=\"dcfa5fa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a5208ec ekit-equal-height-enable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"a5208ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <a href=\"#\" class=\"ekit_global_links\">\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-left text- icon-lef-right-aligin elementor-animation-   \">\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    Linea telefonica diretta                <\/h3>\n                        \t\t  \t<p>Siamo a vostra disposizione per telefono e per e-mail e ci occuperemo delle vostre preoccupazioni. \n<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n                <\/a>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-e283b33\" data-id=\"e283b33\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b6677be ekit-equal-height-enable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"b6677be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <a href=\"#\" class=\"ekit_global_links\">\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text- text- icon-lef-right-aligin elementor-animation-   \">\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    Servizio Remoto                <\/h3>\n                        \t\t  \t<p>I nostri tecnici dell'assistenza in ufficio sono altamente qualificati e risolvono domande e problemi tecnici tramite telefono e manutenzione remota.\n<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n                <\/a>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-45df542\" data-id=\"45df542\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8f67ecf ekit-equal-height-enable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"8f67ecf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <a href=\"#\" class=\"ekit_global_links\">\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text- text- icon-lef-right-aligin elementor-animation-   \">\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    Servizio in loco\/ sul posto                <\/h3>\n                        \t\t  \t<p>Tecnici dell'assistenza addestrati sono costantemente sul posto con i nostri clienti - in tutto il mondo.\n<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n                <\/a>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-935460b elementor-section-content-middle elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"935460b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d4b560e elementor-hidden-mobile\" data-id=\"d4b560e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3c55d1f\" data-id=\"3c55d1f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e7bae8c elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"e7bae8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/hecht.ag\/it\/wp-content\/uploads\/sites\/5\/2022\/12\/2019-Hecht-Gebaeude-2_hecht-ag-Besigheim-unternehmen-maschinenbau-anlagenbau_mobil.jpg\" class=\"attachment-large size-large wp-image-4693\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2dc4760 elementor-widget elementor-widget-heading\" data-id=\"2dc4760\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Ovviamente, HECHT AG accompagna personalmente i propri clienti anche dopo l'acquisto. <br>\nI sistemi HECHT vengono controllati, calibrati o riparati in loco su richiesta. <br>\nLa formazione e le istruzioni si svolgono direttamente sulle macchine presso la vostra sede o presso la nostra. Su richiesta, offriamo aggiornamenti del software. Le modernizzazioni attraverso aggiornamenti software e hardware possono essere discusse e realizzate insieme a noi. Il nostro personale ben addestrato e competente sar\u00e0 lieto di consigliarvi.\n\n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d7e6769 elementor-mobile-align-center elementor-hidden-mobile elementor-align-center elementor-widget elementor-widget-button\" data-id=\"d7e6769\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#formular\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">CONTATTO<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8a850f3 elementor-hidden-tablet elementor-hidden-mobile\" data-id=\"8a850f3\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5ad15b4 elementor-section-content-middle elementor-hidden-desktop elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5ad15b4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-de126d8 elementor-hidden-mobile\" data-id=\"de126d8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-81a2d20\" data-id=\"81a2d20\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-28dc993 elementor-widget elementor-widget-heading\" data-id=\"28dc993\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Ovviamente, HECHT AG accompagna personalmente i propri clienti anche dopo l'acquisto.<br>\nI sistemi HECHT vengono controllati, calibrati o riparati in loco su richiesta. <br>\nLa formazione e le istruzioni si svolgono direttamente sulle macchine presso la vostra sede o presso la nostra. Su richiesta, offriamo aggiornamenti del software. Le modernizzazioni attraverso aggiornamenti software e hardware possono essere discusse e realizzate insieme a noi. Il nostro personale ben addestrato e competente sar\u00e0 lieto di consigliarvi.\n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52675c9 elementor-mobile-align-center elementor-hidden-mobile elementor-align-center elementor-hidden-tablet elementor-widget elementor-widget-button\" data-id=\"52675c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#formular\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Modulo di Contatto<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-47f5515 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"47f5515\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-756da07\" data-id=\"756da07\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e125d6e elementor-widget elementor-widget-heading\" data-id=\"e125d6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Telefono<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd386fb elementor-widget elementor-widget-heading\" data-id=\"dd386fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\"><a href=\"tel:+49714381590\">+49 (0)7143-8159-10<\/a><\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-82accff elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"82accff\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e79e798\" data-id=\"e79e798\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-53aa46c elementor-widget elementor-widget-menu-anchor\" data-id=\"53aa46c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"formular\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d461c76 elementor-widget elementor-widget-heading\" data-id=\"d461c76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Modulo di Contatto<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8c9abc1 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8c9abc1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-d33e461\" data-id=\"d33e461\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-623a760 elementor-widget elementor-widget-shortcode\" data-id=\"623a760\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f6-o1\" lang=\"de-DE\" dir=\"ltr\" data-wpcf7-id=\"6\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/it\/wp-json\/wp\/v2\/pages\/1849#wpcf7-f6-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Kontaktformular\" enctype=\"multipart\/form-data\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"6\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"de_DE\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f6-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"Firma\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Azienda\" value=\"\" type=\"text\" name=\"Firma\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"Vorname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nome\" value=\"\" type=\"text\" name=\"Vorname\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"Nachname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Cognome\" value=\"\" type=\"text\" name=\"Nachname\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"StrasseHausnummer\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Via e numero civico\" value=\"\" type=\"text\" name=\"StrasseHausnummer\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"PLZOrt\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Codice postale\/citt\u00e0\" value=\"\" type=\"text\" name=\"PLZOrt\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"Land\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Paese\" value=\"\" type=\"text\" name=\"Land\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"Telefon\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Telefono\" value=\"\" type=\"tel\" name=\"Telefon\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"eMail\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-Mail\" value=\"\" type=\"email\" name=\"eMail\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"Nachricht\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Message\" name=\"Nachricht\"><\/textarea><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"file-786\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-file\" id=\"datei1337\" accept=\".jpg,.png,.pdf,.gif,.zip\" aria-invalid=\"false\" type=\"file\" name=\"file-786\" \/><\/span><br \/>\nFormati di file consentiti: JPG, PNG, PDF, GIF e ZIP\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-224\"><span class=\"wpcf7-form-control wpcf7-acceptance optional\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"acceptance-224\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">S\u00ec, ho letto l'informativa sulla privacy e accetto che i dati da me forniti vengano raccolti e conservati elettronicamente. I miei dati saranno utilizzati esclusivamente per elaborare e rispondere alla mia richiesta. Inviando il modulo di contatto, acconsento al trattamento dei miei dati.<\/span><\/label><\/span><\/span><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" id=\"button1337\" type=\"submit\" value=\"Invia\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55ec816 elementor-widget elementor-widget-menu-anchor\" data-id=\"55ec816\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"adresse\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-23f84e9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"23f84e9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-513cd49\" data-id=\"513cd49\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b3efc38 elementor-widget elementor-widget-heading\" data-id=\"b3efc38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Come trovarci<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b2fcef elementor-widget elementor-widget-heading\" data-id=\"9b2fcef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Indirizzo<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6469b4 elementor-widget elementor-widget-heading\" data-id=\"a6469b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><b>HECHT<\/b><b> AG<\/b><br>\nOttmarsheimer H\u00f6he<br>\nHeinrich-Hertz-Str. 3-5<br>\n74354 Besigheim<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d52e56 elementor-hidden-mobile elementor-widget elementor-widget-google_maps\" data-id=\"9d52e56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"google-maps\" data-borlabs-cookie-content=\"PGlmcmFtZSBsb2FkaW5nPSJsYXp5IgoJCQkJCXNyYz0iaHR0cHM6Ly9tYXBzLmdvb2dsZS5jb20vbWFwcz9xPUhlY2h0JTIwQUclMjBIZWlucmljaC1IZXJ0ei1TdHIuJTIwMy01JTIwNzQzNTQlMjBCZXNpZ2hlaW0mIzAzODt0PW0mIzAzODt6PTExJiMwMzg7b3V0cHV0PWVtYmVkJiMwMzg7aXdsb2M9bmVhciIKCQkJCQl0aXRsZT0iSGVjaHQgQUcgSGVpbnJpY2gtSGVydHotU3RyLiAzLTUgNzQzNTQgQmVzaWdoZWltIgoJCQkJCWFyaWEtbGFiZWw9IkhlY2h0IEFHIEhlaW5yaWNoLUhlcnR6LVN0ci4gMy01IDc0MzU0IEJlc2lnaGVpbSIKCQkJPjwvaWZyYW1lPg==\"><div class=\"brlbs-cmpnt-cb-preset-b brlbs-cmpnt-cb-google-maps\"> <div class=\"brlbs-cmpnt-cb-thumbnail\" style=\"background-image: url('https:\/\/hecht.ag\/it\/wp-content\/uploads\/borlabs-cookie\/5\/brlbs-cb-google-maps-main.png')\"><\/div> <div class=\"brlbs-cmpnt-cb-main\"> <div class=\"brlbs-cmpnt-cb-content\"> <p class=\"brlbs-cmpnt-cb-description\">Stai visualizzando un contenuto segnaposto da <strong>Google Maps<\/strong>. Per accedere al contenuto effettivo, clicca sul pulsante sottostante. Si prega di notare che in questo modo si condividono i dati con provider di terze parti.<\/p> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Ulteriori informazioni<\/a> <\/div> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Sblocca il contenuto<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Accetta il servizio richiesto e sblocca i contenuti<\/a> <\/div> <\/div> <\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a31fa95 elementor-section-full_width elementor-section-height-min-height elementor-hidden-tablet elementor-hidden-mobile elementor-section-height-default elementor-section-items-middle\" data-id=\"a31fa95\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;_ha_eqh_enable&quot;:false,&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-992756a\" data-id=\"992756a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>SERVIZIO &#038; CONSULENZA Servizio completo da parte dei vostri specialisti: offriamo un servizio a tutto tondo perch\u00e9 sappiamo che la vostra produzione deve raggiungere uno speciale standard di qualit\u00e0. Telefono: +49 (0)7143-8159-10 Modulo di Contatto Stai visualizzando un contenuto segnaposto da Google Maps. Per accedere al contenuto effettivo, clicca sul pulsante sottostante. Si prega di [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-1849","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"SERVIZIO &amp; CONSULENZA Servizio completo da parte dei vostri specialisti: offriamo un servizio a tutto tondo perch\u00e9 sappiamo che la vostra produzione deve raggiungere uno speciale standard di qualit\u00e0. Telefono: +49 (0)7143-8159-10 Modulo di Contatto Stai visualizzando un contenuto segnaposto da Google Maps. Per accedere al contenuto effettivo, clicca sul pulsante sottostante. Si prega di\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/hecht.ag\/it\/servizio-consulenza\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"it_IT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Hecht AG - Italian - Hecht Electronic AG offre sistemi di misura e posizionamento innovativi, economici e tecnologicamente avanzati, tra cui fermi di lunghezza come il fermo di lunghezza Exenso e tavoli di misura come il tavolo di misura Opto-DesQ Vmax per il controllo della qualit\u00e0 ottica.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"SERVIZIO &amp; CONSULENZA\u200b - Hecht AG\" \/>\n\t\t<meta property=\"og:description\" content=\"SERVIZIO &amp; CONSULENZA Servizio completo da parte dei vostri specialisti: offriamo un servizio a tutto tondo perch\u00e9 sappiamo che la vostra produzione deve raggiungere uno speciale standard di qualit\u00e0. Telefono: +49 (0)7143-8159-10 Modulo di Contatto Stai visualizzando un contenuto segnaposto da Google Maps. Per accedere al contenuto effettivo, clicca sul pulsante sottostante. Si prega di\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/hecht.ag\/it\/servizio-consulenza\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/hecht.ag\/it\/wp-content\/uploads\/sites\/5\/2022\/11\/Hecht-Logo.png.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/hecht.ag\/it\/wp-content\/uploads\/sites\/5\/2022\/11\/Hecht-Logo.png.jpg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-11-28T08:32:10+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-03-28T08:14:08+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"SERVIZIO &amp; CONSULENZA\u200b - Hecht AG\" \/>\n\t\t<meta name=\"twitter:description\" content=\"SERVIZIO &amp; CONSULENZA Servizio completo da parte dei vostri specialisti: offriamo un servizio a tutto tondo perch\u00e9 sappiamo che la vostra produzione deve raggiungere uno speciale standard di qualit\u00e0. Telefono: +49 (0)7143-8159-10 Modulo di Contatto Stai visualizzando un contenuto segnaposto da Google Maps. Per accedere al contenuto effettivo, clicca sul pulsante sottostante. Si prega di\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/hecht.ag\/it\/wp-content\/uploads\/sites\/5\/2022\/11\/Hecht-Logo.png.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hecht.ag\\\/it\\\/servizio-consulenza\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/hecht.ag\\\/it#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hecht.ag\\\/it\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/hecht.ag\\\/it\\\/servizio-consulenza\\\/#listItem\",\"name\":\"SERVIZIO &#038; CONSULENZA\\u200b\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/hecht.ag\\\/it\\\/servizio-consulenza\\\/#listItem\",\"position\":2,\"name\":\"SERVIZIO &#038; CONSULENZA\\u200b\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/hecht.ag\\\/it#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hecht.ag\\\/it\\\/#organization\",\"name\":\"Hecht AG\",\"description\":\"Hecht Electronic AG offre sistemi di misura e posizionamento innovativi, economici e tecnologicamente avanzati, tra cui fermi di lunghezza come il fermo di lunghezza Exenso e tavoli di misura come il tavolo di misura Opto-DesQ Vmax per il controllo della qualit\\u00e0 ottica.\",\"url\":\"https:\\\/\\\/hecht.ag\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/hecht.ag\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2022\\\/11\\\/Hecht-Logo.png.jpg\",\"@id\":\"https:\\\/\\\/hecht.ag\\\/it\\\/servizio-consulenza\\\/#organizationLogo\",\"width\":573,\"height\":228},\"image\":{\"@id\":\"https:\\\/\\\/hecht.ag\\\/it\\\/servizio-consulenza\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hecht.ag\\\/it\\\/servizio-consulenza\\\/#webpage\",\"url\":\"https:\\\/\\\/hecht.ag\\\/it\\\/servizio-consulenza\\\/\",\"name\":\"SERVIZIO & CONSULENZA\\u200b - Hecht AG\",\"description\":\"SERVIZIO & CONSULENZA Servizio completo da parte dei vostri specialisti: offriamo un servizio a tutto tondo perch\\u00e9 sappiamo che la vostra produzione deve raggiungere uno speciale standard di qualit\\u00e0. Telefono: +49 (0)7143-8159-10 Modulo di Contatto Stai visualizzando un contenuto segnaposto da Google Maps. Per accedere al contenuto effettivo, clicca sul pulsante sottostante. Si prega di\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hecht.ag\\\/it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hecht.ag\\\/it\\\/servizio-consulenza\\\/#breadcrumblist\"},\"datePublished\":\"2022-11-28T09:32:10+01:00\",\"dateModified\":\"2024-03-28T09:14:08+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hecht.ag\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/hecht.ag\\\/it\\\/\",\"name\":\"Hecht AG\",\"description\":\"Hecht Electronic AG offre sistemi di misura e posizionamento innovativi, economici e tecnologicamente avanzati, tra cui fermi di lunghezza come il fermo di lunghezza Exenso e tavoli di misura come il tavolo di misura Opto-DesQ Vmax per il controllo della qualit\\u00e0 ottica.\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/hecht.ag\\\/it\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"SERVIZIO & CONSULENZA\u200b - Hecht AG","description":"SERVIZIO & CONSULENZA Servizio completo da parte dei vostri specialisti: offriamo un servizio a tutto tondo perch\u00e9 sappiamo che la vostra produzione deve raggiungere uno speciale standard di qualit\u00e0. Telefono: +49 (0)7143-8159-10 Modulo di Contatto Stai visualizzando un contenuto segnaposto da Google Maps. Per accedere al contenuto effettivo, clicca sul pulsante sottostante. Si prega di","canonical_url":"https:\/\/hecht.ag\/it\/servizio-consulenza\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/hecht.ag\/it\/servizio-consulenza\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/hecht.ag\/it#listItem","position":1,"name":"Home","item":"https:\/\/hecht.ag\/it","nextItem":{"@type":"ListItem","@id":"https:\/\/hecht.ag\/it\/servizio-consulenza\/#listItem","name":"SERVIZIO &#038; CONSULENZA\u200b"}},{"@type":"ListItem","@id":"https:\/\/hecht.ag\/it\/servizio-consulenza\/#listItem","position":2,"name":"SERVIZIO &#038; CONSULENZA\u200b","previousItem":{"@type":"ListItem","@id":"https:\/\/hecht.ag\/it#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/hecht.ag\/it\/#organization","name":"Hecht AG","description":"Hecht Electronic AG offre sistemi di misura e posizionamento innovativi, economici e tecnologicamente avanzati, tra cui fermi di lunghezza come il fermo di lunghezza Exenso e tavoli di misura come il tavolo di misura Opto-DesQ Vmax per il controllo della qualit\u00e0 ottica.","url":"https:\/\/hecht.ag\/it\/","logo":{"@type":"ImageObject","url":"https:\/\/hecht.ag\/it\/wp-content\/uploads\/sites\/5\/2022\/11\/Hecht-Logo.png.jpg","@id":"https:\/\/hecht.ag\/it\/servizio-consulenza\/#organizationLogo","width":573,"height":228},"image":{"@id":"https:\/\/hecht.ag\/it\/servizio-consulenza\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/hecht.ag\/it\/servizio-consulenza\/#webpage","url":"https:\/\/hecht.ag\/it\/servizio-consulenza\/","name":"SERVIZIO & CONSULENZA\u200b - Hecht AG","description":"SERVIZIO & CONSULENZA Servizio completo da parte dei vostri specialisti: offriamo un servizio a tutto tondo perch\u00e9 sappiamo che la vostra produzione deve raggiungere uno speciale standard di qualit\u00e0. Telefono: +49 (0)7143-8159-10 Modulo di Contatto Stai visualizzando un contenuto segnaposto da Google Maps. Per accedere al contenuto effettivo, clicca sul pulsante sottostante. Si prega di","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/hecht.ag\/it\/#website"},"breadcrumb":{"@id":"https:\/\/hecht.ag\/it\/servizio-consulenza\/#breadcrumblist"},"datePublished":"2022-11-28T09:32:10+01:00","dateModified":"2024-03-28T09:14:08+01:00"},{"@type":"WebSite","@id":"https:\/\/hecht.ag\/it\/#website","url":"https:\/\/hecht.ag\/it\/","name":"Hecht AG","description":"Hecht Electronic AG offre sistemi di misura e posizionamento innovativi, economici e tecnologicamente avanzati, tra cui fermi di lunghezza come il fermo di lunghezza Exenso e tavoli di misura come il tavolo di misura Opto-DesQ Vmax per il controllo della qualit\u00e0 ottica.","inLanguage":"it-IT","publisher":{"@id":"https:\/\/hecht.ag\/it\/#organization"}}]},"og:locale":"it_IT","og:site_name":"Hecht AG - Italian - Hecht Electronic AG offre sistemi di misura e posizionamento innovativi, economici e tecnologicamente avanzati, tra cui fermi di lunghezza come il fermo di lunghezza Exenso e tavoli di misura come il tavolo di misura Opto-DesQ Vmax per il controllo della qualit\u00e0 ottica.","og:type":"article","og:title":"SERVIZIO &amp; CONSULENZA\u200b - Hecht AG","og:description":"SERVIZIO &amp; CONSULENZA Servizio completo da parte dei vostri specialisti: offriamo un servizio a tutto tondo perch\u00e9 sappiamo che la vostra produzione deve raggiungere uno speciale standard di qualit\u00e0. Telefono: +49 (0)7143-8159-10 Modulo di Contatto Stai visualizzando un contenuto segnaposto da Google Maps. Per accedere al contenuto effettivo, clicca sul pulsante sottostante. Si prega di","og:url":"https:\/\/hecht.ag\/it\/servizio-consulenza\/","og:image":"https:\/\/hecht.ag\/it\/wp-content\/uploads\/sites\/5\/2022\/11\/Hecht-Logo.png.jpg","og:image:secure_url":"https:\/\/hecht.ag\/it\/wp-content\/uploads\/sites\/5\/2022\/11\/Hecht-Logo.png.jpg","article:published_time":"2022-11-28T08:32:10+00:00","article:modified_time":"2024-03-28T08:14:08+00:00","twitter:card":"summary_large_image","twitter:title":"SERVIZIO &amp; CONSULENZA\u200b - Hecht AG","twitter:description":"SERVIZIO &amp; CONSULENZA Servizio completo da parte dei vostri specialisti: offriamo un servizio a tutto tondo perch\u00e9 sappiamo che la vostra produzione deve raggiungere uno speciale standard di qualit\u00e0. Telefono: +49 (0)7143-8159-10 Modulo di Contatto Stai visualizzando un contenuto segnaposto da Google Maps. Per accedere al contenuto effettivo, clicca sul pulsante sottostante. Si prega di","twitter:image":"https:\/\/hecht.ag\/it\/wp-content\/uploads\/sites\/5\/2022\/11\/Hecht-Logo.png.jpg"},"aioseo_meta_data":{"post_id":"1849","title":"#post_title #separator_sa Hecht AG","description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_custom_url":null,"og_image_custom_fields":null,"og_custom_image_width":null,"og_custom_image_height":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"none","tabs":null,"priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"created":"2023-11-26 19:12:35","updated":"2026-06-29 20:13:52","og_image_url":null,"og_image_width":null,"og_image_height":null,"twitter_image_url":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"limit_modified_date":false,"ai":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/hecht.ag\/it\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSERVIZIO &amp; CONSULENZA\u200b\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/hecht.ag\/it"},{"label":"SERVIZIO &#038; CONSULENZA\u200b","link":"https:\/\/hecht.ag\/it\/servizio-consulenza\/"}],"_links":{"self":[{"href":"https:\/\/hecht.ag\/it\/wp-json\/wp\/v2\/pages\/1849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hecht.ag\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hecht.ag\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hecht.ag\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hecht.ag\/it\/wp-json\/wp\/v2\/comments?post=1849"}],"version-history":[{"count":10,"href":"https:\/\/hecht.ag\/it\/wp-json\/wp\/v2\/pages\/1849\/revisions"}],"predecessor-version":[{"id":11778,"href":"https:\/\/hecht.ag\/it\/wp-json\/wp\/v2\/pages\/1849\/revisions\/11778"}],"wp:attachment":[{"href":"https:\/\/hecht.ag\/it\/wp-json\/wp\/v2\/media?parent=1849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}